{"id":236,"count":4,"description":"","link":"https:\/\/brymmo.com\/de\/espaces-exterieurs\/groszugiger-ausenbereich\/","name":"Gro\u00dfz\u00fcgiger Au\u00dfenbereich","slug":"groszugiger-ausenbereich","taxonomy":"espaces-exterieurs","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/brymmo.com\/de\/wp-json\/wp\/v2\/espaces-exterieurs\/236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brymmo.com\/de\/wp-json\/wp\/v2\/espaces-exterieurs"}],"about":[{"href":"https:\/\/brymmo.com\/de\/wp-json\/wp\/v2\/taxonomies\/espaces-exterieurs"}],"wp:post_type":[{"href":"https:\/\/brymmo.com\/de\/wp-json\/wp\/v2\/biens?espaces-exterieurs=236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}